{"id":407834,"date":"2024-06-26T08:30:18","date_gmt":"2024-06-26T13:30:18","guid":{"rendered":"https:\/\/wptpower.com\/?p=407834"},"modified":"2024-06-26T08:30:20","modified_gmt":"2024-06-26T13:30:20","slug":"wpt-da-la-bienvenida-a-melody-johnson-representante-de-ventas-internas","status":"publish","type":"post","link":"https:\/\/wptpower.com\/es\/wpt-da-la-bienvenida-a-melody-johnson-representante-de-ventas-internas\/","title":{"rendered":"WPT Da la Bienvenida a Melody Johnson, Representante de Ventas Internas"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"538\" data-attachment-id=\"407833\" data-permalink=\"https:\/\/wptpower.com\/es\/melody-johnson\/\" data-orig-file=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson.png\" data-orig-size=\"1200,630\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Melody Johnson Announcement\" data-image-description=\"&lt;p&gt;Melody Johnson Inside Sales Representative&lt;\/p&gt;\" data-image-caption=\"\" data-large-file=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-1024x538.png\" src=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-ES-min.png\" alt=\"Melody Johnson Representante de Ventas\" class=\"wp-image-407833\" srcset=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-ES-min.png 1200w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-ES-min-300x158.png 300w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-ES-min-1024x538.png 1024w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-ES-min-768x403.png 768w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-ES-min-18x9.png 18w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson-ES-min-600x315.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>WPT Power est\u00e1 oficialmente orgulloso de anunciar que Melody Johnson se ha unido a nuestro equipo como Representante de Ventas Internas. La gran experiencia de Melody en atenci\u00f3n al cliente y responsabilidades administrativas, as\u00ed como su exitosa trayectoria como propietaria y gerente de un estudio fotogr\u00e1fico, la convierten en una valiosa incorporaci\u00f3n a nuestro equipo de ventas. Su funci\u00f3n principal consistir\u00e1 en investigar y desarrollar cuentas potenciales, evaluar internamente las necesidades de los clientes y ofrecer soluciones de producto. Trabajar\u00e1 en estrecha colaboraci\u00f3n con Ingenier\u00eda de Aplicaciones y Atenci\u00f3n al Cliente, que son cruciales para nuestras operaciones.<\/p>\n\n\n\n<p><em>\"Estamos encantados de que Melody forme parte de la familia del WPT y de aportar su experiencia\". <\/em>afirma Brett Emson, Director de Ventas de WPT. <em>\"Tiene grandes dotes organizativas y podr\u00e1 proporcionar a WPT Power direcci\u00f3n estrat\u00e9gica, planificaci\u00f3n y apoyo a nuestro equipo de Ventas\".<\/em><\/p>\n\n\n\n<p>\u00a1Estamos muy contentos de dar la bienvenida a Melody a la familia WPT a medida que continuamos creciendo y fortaleciendo nuestro equipo de ventas!<\/p>","protected":false},"excerpt":{"rendered":"<p>WPT Power est\u00e1 oficialmente orgulloso de anunciar que Melody Johnson se ha unido a nuestro equipo como Representante de Ventas Internas. La gran experiencia de Melody en servicio al cliente y responsabilidades administrativas, as\u00ed como su exitosa permanencia como propietaria y gerente de un estudio de fotograf\u00eda, la convierten en una valiosa incorporaci\u00f3n a nuestro equipo de ventas. Su principal [...]<\/p>","protected":false},"author":2,"featured_media":407833,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[499],"tags":[],"wpt_product_type":[],"wpt_industry":[448],"class_list":["post-407834","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-employee","wpt_industry-miscellaneous"],"jetpack_featured_media_url":"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/06\/Melody-Johnson.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts\/407834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/comments?post=407834"}],"version-history":[{"count":0,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts\/407834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/media\/407833"}],"wp:attachment":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/media?parent=407834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/categories?post=407834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/tags?post=407834"},{"taxonomy":"wpt_product_type","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/wpt_product_type?post=407834"},{"taxonomy":"wpt_industry","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/wpt_industry?post=407834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}