{"id":407840,"date":"2024-07-02T09:21:41","date_gmt":"2024-07-02T14:21:41","guid":{"rendered":"https:\/\/wptpower.com\/?p=407840"},"modified":"2024-07-02T09:21:45","modified_gmt":"2024-07-02T14:21:45","slug":"michael-allen-se-incorpora-a-wpt-power-como-director-de-ingenieria","status":"publish","type":"post","link":"https:\/\/wptpower.com\/es\/michael-allen-se-incorpora-a-wpt-power-como-director-de-ingenieria\/","title":{"rendered":"Michael Allen se Incorpora a WPT Power Como Director de Ingenier\u00eda"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"538\" data-attachment-id=\"407839\" data-permalink=\"https:\/\/wptpower.com\/es\/michael_allen\/\" data-orig-file=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/Michael_Allen.png\" data-orig-size=\"1200,630\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Michael_Allen\" data-image-description=\"&lt;p&gt;Michael Allen Director of Engineering announcement&lt;\/p&gt;\" data-image-caption=\"\" data-large-file=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/Michael_Allen-1024x538.png\" src=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/M_Allen-ES.png\" alt=\"Ingenier\u00eda Michael Allen\" class=\"wp-image-407839\" srcset=\"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/M_Allen-ES.png 1200w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/M_Allen-ES-300x158.png 300w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/M_Allen-ES-1024x538.png 1024w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/M_Allen-ES-768x403.png 768w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/M_Allen-ES-18x9.png 18w, https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/M_Allen-ES-600x315.png 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">WPT Power se complace en anunciar su m\u00e1s reciente contrataci\u00f3n, Michael Allen, que se unir\u00e1 al equipo de WPT como Director de Ingenier\u00eda. Allen trae m\u00e1s de una d\u00e9cada de dise\u00f1o de ingenier\u00eda mec\u00e1nica y experiencia en desarrollo de productos a WPT. M\u00e1s recientemente, Allen fue el Ingeniero de Dise\u00f1o Mec\u00e1nico en el Sheppard AFB del Departamento de Defensa y tiene su empresa, Allen Mechanical Consulting. Antes de eso, fue el Ingeniero Senior de Desarrollo de Producto en Amarillo Gear Company.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Allen es experto en investigaci\u00f3n, desarrollo, dise\u00f1o y fabricaci\u00f3n de componentes hidr\u00e1ulicos, sistemas de elevaci\u00f3n hidr\u00e1ulica y sistemas y componentes de transmisi\u00f3n por engranajes de \u00e1ngulo recto. Ha formado parte del Comit\u00e9 T\u00e9cnico de la Asociaci\u00f3n Americana de Fabricantes de Engranajes (AGMA), contribuyendo al establecimiento de normas industriales. La comprensi\u00f3n y el discernimiento de Michael en ingenier\u00eda han dado lugar a una patente de la USPTO, as\u00ed como a otras muchas ideas innovadoras. Su experiencia, que no s\u00f3lo es amplia sino tambi\u00e9n muy relevante para nuestras operaciones, ser\u00e1 una valiosa incorporaci\u00f3n a nuestra familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>La contrataci\u00f3n de Allen encajar\u00e1 perfectamente en la empresa. \"Estamos encantados de tener a Michael en nuestro equipo. Los clientes se dar\u00e1n cuenta de los beneficios de construir y mejorar el liderazgo de nuestro departamento de ingenier\u00eda\",<\/em> ha declarado Byron Baber, Vicepresidente de WPT Power. <em>\"Estamos seguros de que su experiencia y conocimientos contribuir\u00e1n significativamente al crecimiento de nuestra l\u00ednea de productos y a la mejora continua\".<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>WPT Power se complace en anunciar su m\u00e1s reciente contrataci\u00f3n, Michael Allen, que se unir\u00e1 al equipo de WPT como Director de Ingenier\u00eda. Allen trae m\u00e1s de una d\u00e9cada de dise\u00f1o de ingenier\u00eda mec\u00e1nica y experiencia en desarrollo de productos a WPT. M\u00e1s recientemente, Allen fue el Ingeniero de Dise\u00f1o Mec\u00e1nico en el Departamento de Defensa Sheppard AFB ubicaci\u00f3n y [...]<\/p>","protected":false},"author":2,"featured_media":407839,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[499],"tags":[12],"wpt_product_type":[],"wpt_industry":[448],"class_list":["post-407840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-employee","tag-news","wpt_industry-miscellaneous"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/wptpower.com\/wp-content\/uploads\/2024\/07\/Michael_Allen.png","_links":{"self":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts\/407840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/comments?post=407840"}],"version-history":[{"count":0,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts\/407840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/media\/407839"}],"wp:attachment":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/media?parent=407840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/categories?post=407840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/tags?post=407840"},{"taxonomy":"wpt_product_type","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/wpt_product_type?post=407840"},{"taxonomy":"wpt_industry","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/wpt_industry?post=407840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}