{"id":93674,"date":"2018-09-21T08:23:03","date_gmt":"2018-09-21T14:23:03","guid":{"rendered":"https:\/\/unusual-confetti.flywheelsites.com\/?p=93674"},"modified":"2025-06-06T15:00:30","modified_gmt":"2025-06-06T20:00:30","slug":"la-asistencia-en-equipo-aumenta-el-negocio-de-la-toma-de-fuerza","status":"publish","type":"post","link":"https:\/\/wptpower.com\/es\/la-asistencia-en-equipo-aumenta-el-negocio-de-la-toma-de-fuerza\/","title":{"rendered":"El Apoyo en Equipo Aumenta el Negocio de Tomas de Fuerza Para Trituradoras"},"content":{"rendered":"<p>Nunca es un buen momento para que se produzca un fallo en un equipo, y ese fue sin duda el caso de este cliente de Wyoming. Un cojinete principal defectuoso en la toma de fuerza mec\u00e1nica de un competidor paraliz\u00f3 su amoladora. Para empeorar las cosas, la placa de identificaci\u00f3n estaba mal etiquetada, indicando especificaciones de embrague incorrectas, lo que aument\u00f3 la frustraci\u00f3n durante un tiempo de inactividad ya de por s\u00ed costoso e inesperado.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"93709\" data-permalink=\"https:\/\/wptpower.com\/es\/la-asistencia-en-equipo-aumenta-el-negocio-de-la-toma-de-fuerza\/wpt-timco-2-lo\/\" data-orig-file=\"https:\/\/wptpower.com\/wp-content\/uploads\/2018\/09\/WPT-TIMCO-2-lo.jpg\" data-orig-size=\"307,480\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mechanical PTO on Grinder\" data-image-description=\"&lt;p&gt;WPT replacement power take-off for grinder&lt;\/p&gt;\" data-image-caption=\"\" data-large-file=\"https:\/\/wptpower.com\/wp-content\/uploads\/2018\/09\/WPT-TIMCO-2-lo.jpg\" class=\"alignright wp-image-93709\" src=\"https:\/\/wptpower.com\/wp-content\/uploads\/2018\/09\/WPT-TIMCO-2-lo-192x300.jpg\" alt=\"aplicaci\u00f3n de toma de fuerza mec\u00e1nica en amoladora\" width=\"201\" height=\"305\" \/>TIMCO y el ingeniero de aplicaciones de WPT hab\u00edan trabajado juntos con el cliente en una instalaci\u00f3n anterior con gran \u00e9xito. Cuando su segunda unidad dej\u00f3 de funcionar, les llamaron para determinar cu\u00e1l era la sustituci\u00f3n m\u00e1s adecuada. TIMCO revis\u00f3 las especificaciones del cliente y\u00a0<span style=\"box-sizing: border-box; margin: 0px; padding: 0px;\">determin\u00f3 que el producto m\u00e1s adecuado para esta aplicaci\u00f3n ser\u00eda un\u00a0<a href=\"https:\/\/wptpower.com\/es\/producto\/toma-de-fuerza-mecanica\/\" target=\"_blank\" rel=\"noopener\">WTD-11-13F<\/a><\/span>que inclu\u00eda una mayor capacidad de carga lateral. Con algunas modificaciones personalizadas, una unidad WPT fiable y de alta calidad result\u00f3 m\u00e1s asequible y menos complicada mec\u00e1nicamente que el producto del antiguo competidor.<\/p>\n<p><span style=\"color: initial; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">Adem\u00e1s de ofrecer un excelente nivel de asistencia, <\/span><a style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" href=\"https:\/\/wptpower.com\/es\/distribuidores\/norteamerica\/usa\/listado4-2\/\" target=\"_blank\" rel=\"noopener\">TIMCO<\/a><span style=\"color: initial; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\"> es muy diligente a la hora de mantener un inventario bien surtido de productos.<\/span> Eso se traduce en que el cliente dispondr\u00e1 de repuestos r\u00e1pidamente, minimizando el tiempo de inactividad. Gracias a la experiencia y la calidad demostradas en la instalaci\u00f3n anterior de la rectificadora de juntas, este cliente seleccionar\u00e1 inicialmente a TIMCO y WPT.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nunca es un buen momento para que se produzca un fallo en un equipo, y ese fue sin duda el caso de este cliente de Wyoming. Un cojinete principal defectuoso en la toma de fuerza mec\u00e1nica de un competidor paraliz\u00f3 su amoladora. Para empeorar las cosas, la placa de identificaci\u00f3n estaba mal etiquetada, indicando especificaciones de embrague incorrectas, lo que aument\u00f3 la frustraci\u00f3n durante una [...]<\/p>","protected":false},"author":2,"featured_media":93709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[76,223],"tags":[240,133,131,132],"wpt_product_type":[434],"wpt_industry":[444],"class_list":["post-93674","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-applications-blog","category-power-take-off","tag-grinder-pto","tag-mechanical-pto","tag-power-take-off","tag-pto","post_format-post-format-image","wpt_product_type-engine-driven","wpt_industry-mining-aggregates"],"jetpack_featured_media_url":"https:\/\/wptpower.com\/wp-content\/uploads\/2018\/09\/WPT-TIMCO-2-lo.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts\/93674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/comments?post=93674"}],"version-history":[{"count":0,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/posts\/93674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/media\/93709"}],"wp:attachment":[{"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/media?parent=93674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/categories?post=93674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/tags?post=93674"},{"taxonomy":"wpt_product_type","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/wpt_product_type?post=93674"},{"taxonomy":"wpt_industry","embeddable":true,"href":"https:\/\/wptpower.com\/es\/wp-json\/wp\/v2\/wpt_industry?post=93674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}